{"id":1875,"date":"2021-05-14T15:10:43","date_gmt":"2021-05-14T13:10:43","guid":{"rendered":"https:\/\/basbarcelona.com\/?post_type=product&#038;p=1875"},"modified":"2026-03-12T21:27:25","modified_gmt":"2026-03-12T20:27:25","slug":"plantcloud-maceta-colgante","status":"publish","type":"product","link":"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/","title":{"rendered":"Plantcloud"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"1875\" class=\"elementor elementor-1875\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18f17e9 e-flex e-con-boxed e-con e-parent\" data-id=\"18f17e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d490ba8 e-con-full e-flex e-con e-child\" data-id=\"d490ba8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfccaee elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"cfccaee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;slideshow_slides_per_view_tablet&quot;:&quot;6&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"maceta colgante techo\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/11\/aporophyllum.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"maceta colgante de cer\u00e1mica blanca\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-colgante-de-ceramica-blanca.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Detallle-cinta-plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Detallle-cinta-plantcloud.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"detalle-maceta-plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Detalle-cinturon-plantcloud.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"plantcloud cinta grana\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-cinta-grana.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"plantcloud-abierta\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plantcloud-abierta.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"macetero colgante ceramica plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2024\/06\/5732c787-10b4-496b-bb2f-fec07569d755.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Macetero Planta Colgante\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-planta-colgante.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Seg\u00fcent\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Diapositivas Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"maceta colgante techo\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/11\/aporophyllum.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"maceta colgante de cer\u00e1mica blanca\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-colgante-de-ceramica-blanca.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Detallle-cinta-plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Detallle-cinta-plantcloud.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"detalle-maceta-plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Detalle-cinturon-plantcloud.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"plantcloud cinta grana\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-cinta-grana.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"plantcloud-abierta\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plantcloud-abierta.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"macetero colgante ceramica plantcloud\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2024\/06\/5732c787-10b4-496b-bb2f-fec07569d755.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Macetero Planta Colgante\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-planta-colgante.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81464f8 e-con-full e-flex e-con e-child\" data-id=\"81464f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1463f8 elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"f1463f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t\t<h2 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Plantcloud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b34297 elementor-widget elementor-widget-woocommerce-product-short-description\" data-id=\"7b34297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-short-description.default\">\n\t\t\t\t\t<div class=\"woocommerce-product-details__short-description\">\n\t<p>Plantcloud es una maceta colgante sostenible de cer\u00e1mica blanca brillante. Lleva una cinta de cuero vegetal elaborada con los restos de hojas de pi\u00f1a.<\/p>\n<p>Tiene un sistema muy pr\u00e1ctico para el riego y vaciado de agua.<\/p>\n<p><a href=\"https:\/\/basbarcelona.com\/plantcloud\" target=\"_blank\" rel=\"noopener\"><em>m\u00e1s informaci\u00f3n<\/em><\/a><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c781c1f elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"c781c1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>242.00<\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-059fe18 elementor-widget-mobile__width-initial elementor-widget elementor-widget-wl-product-add-to-cart\" data-id=\"059fe18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wl-product-add-to-cart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"wl-addto-cart variable wl-style-2 wl-show-status\">\n                    \n<form class=\"variations_form cart\" action=\"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/\" method=\"post\" enctype='multipart\/form-data' data-product_id=\"1875\" data-product_variations=\"[{&quot;attributes&quot;:{&quot;attribute_pa_color-cinta&quot;:&quot;blanco-perla&quot;},&quot;availability_html&quot;:&quot;&quot;,&quot;backorders_allowed&quot;:false,&quot;dimensions&quot;:{&quot;length&quot;:&quot;20&quot;,&quot;width&quot;:&quot;20&quot;,&quot;height&quot;:&quot;25&quot;},&quot;dimensions_html&quot;:&quot;20 &amp;times; 20 &amp;times; 25 cm&quot;,&quot;display_price&quot;:242,&quot;display_regular_price&quot;:242,&quot;gallery_image_ids&quot;:[],&quot;gallery_images_html&quot;:&quot;&quot;,&quot;image&quot;:{&quot;title&quot;:&quot;maceta-colgante-dise\\u00f1o&quot;,&quot;caption&quot;:&quot;maceta colgante de dise\\u00f1o&quot;,&quot;url&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png&quot;,&quot;alt&quot;:&quot;maceta colgante de dise\\u00f1o&quot;,&quot;src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x716.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x716.png 600w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-252x300.png 252w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-768x916.png 768w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-859x1024.png 859w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png 1200w&quot;,&quot;sizes&quot;:&quot;(max-width: 600px) 100vw, 600px&quot;,&quot;full_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png&quot;,&quot;full_src_w&quot;:1200,&quot;full_src_h&quot;:1431,&quot;gallery_thumbnail_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-100x100.png&quot;,&quot;gallery_thumbnail_src_w&quot;:100,&quot;gallery_thumbnail_src_h&quot;:100,&quot;thumb_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x600.png&quot;,&quot;thumb_src_w&quot;:600,&quot;thumb_src_h&quot;:600,&quot;src_w&quot;:600,&quot;src_h&quot;:716},&quot;image_id&quot;:1633,&quot;is_downloadable&quot;:false,&quot;is_in_stock&quot;:true,&quot;is_purchasable&quot;:true,&quot;is_sold_individually&quot;:&quot;no&quot;,&quot;is_virtual&quot;:false,&quot;max_qty&quot;:&quot;&quot;,&quot;min_qty&quot;:1,&quot;price_html&quot;:&quot;&quot;,&quot;sku&quot;:&quot;plantcloud&quot;,&quot;variation_description&quot;:&quot;&quot;,&quot;variation_id&quot;:1932,&quot;variation_is_active&quot;:true,&quot;variation_is_visible&quot;:true,&quot;weight&quot;:&quot;2&quot;,&quot;weight_html&quot;:&quot;2 kg&quot;},{&quot;attributes&quot;:{&quot;attribute_pa_color-cinta&quot;:&quot;grana&quot;},&quot;availability_html&quot;:&quot;&quot;,&quot;backorders_allowed&quot;:false,&quot;dimensions&quot;:{&quot;length&quot;:&quot;20&quot;,&quot;width&quot;:&quot;20&quot;,&quot;height&quot;:&quot;25&quot;},&quot;dimensions_html&quot;:&quot;20 &amp;times; 20 &amp;times; 25 cm&quot;,&quot;display_price&quot;:242,&quot;display_regular_price&quot;:242,&quot;gallery_image_ids&quot;:[],&quot;gallery_images_html&quot;:&quot;&quot;,&quot;image&quot;:{&quot;title&quot;:&quot;maceta-colgante-dise\\u00f1o&quot;,&quot;caption&quot;:&quot;maceta colgante de dise\\u00f1o&quot;,&quot;url&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png&quot;,&quot;alt&quot;:&quot;maceta colgante de dise\\u00f1o&quot;,&quot;src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x716.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x716.png 600w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-252x300.png 252w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-768x916.png 768w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-859x1024.png 859w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png 1200w&quot;,&quot;sizes&quot;:&quot;(max-width: 600px) 100vw, 600px&quot;,&quot;full_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra.png&quot;,&quot;full_src_w&quot;:1200,&quot;full_src_h&quot;:1431,&quot;gallery_thumbnail_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-100x100.png&quot;,&quot;gallery_thumbnail_src_w&quot;:100,&quot;gallery_thumbnail_src_h&quot;:100,&quot;thumb_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/plancloud-sombra-600x600.png&quot;,&quot;thumb_src_w&quot;:600,&quot;thumb_src_h&quot;:600,&quot;src_w&quot;:600,&quot;src_h&quot;:716},&quot;image_id&quot;:1633,&quot;is_downloadable&quot;:false,&quot;is_in_stock&quot;:true,&quot;is_purchasable&quot;:true,&quot;is_sold_individually&quot;:&quot;no&quot;,&quot;is_virtual&quot;:false,&quot;max_qty&quot;:&quot;&quot;,&quot;min_qty&quot;:1,&quot;price_html&quot;:&quot;&quot;,&quot;sku&quot;:&quot;plantcloud&quot;,&quot;variation_description&quot;:&quot;&quot;,&quot;variation_id&quot;:1933,&quot;variation_is_active&quot;:true,&quot;variation_is_visible&quot;:true,&quot;weight&quot;:&quot;2&quot;,&quot;weight_html&quot;:&quot;2 kg&quot;}]\">\n\t\n\t\t\t<table class=\"variations\" cellspacing=\"0\" role=\"presentation\">\n\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t<th class=\"label\"><label for=\"pa_color-cinta\">Color cinta:<\/label><\/th>\n\t\t\t\t\t\t<td class=\"value\">\n\t\t\t\t\t\t\t<select id=\"pa_color-cinta\" class=\"\" name=\"attribute_pa_color-cinta\" data-attribute_name=\"attribute_pa_color-cinta\" data-show_option_none=\"yes\"><option value=\"\">Trieu una opci\u00f3<\/option><option value=\"blanco-perla\" >Blanco Perla<\/option><option value=\"grana\" >Grana<\/option><\/select><a class=\"reset_variations\" href=\"#\" aria-label=\"Neteja les opcions\">Neteja<\/a>\t\t\t\t\t\t<\/td>\n\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t<\/table>\n\t\t<div class=\"reset_variations_alert screen-reader-text\" role=\"alert\" aria-live=\"polite\" aria-relevant=\"all\"><\/div>\n\t\t\t\t\n\t\t<div class=\"single_variation_wrap\">\n\t\t\t<div class=\"woocommerce-variation single_variation\" role=\"alert\" aria-relevant=\"additions\"><\/div><div class=\"woocommerce-variation-add-to-cart variations_button\">\n\t\n\t<div class=\"wl-quantity-wrap\"><span class=\"label\">Quantity<\/span><div class=\"wl-quantity-cal\"><span class=\"wl-quantity wl-quantity-minus\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span><div class=\"quantity\">\n\t\t<label class=\"screen-reader-text\" for=\"quantity_6a57520d4c5f5\">quantitat de Plantcloud<\/label>\n\t<input\n\t\ttype=\"number\"\n\t\t\t\tid=\"quantity_6a57520d4c5f5\"\n\t\tclass=\"input-text qty text\"\n\t\tname=\"quantity\"\n\t\tvalue=\"1\"\n\t\taria-label=\"Quantitat de producte\"\n\t\t\t\tmin=\"1\"\n\t\t\t\t\t\t\tstep=\"1\"\n\t\t\tplaceholder=\"\"\n\t\t\tinputmode=\"numeric\"\n\t\t\tautocomplete=\"off\"\n\t\t\t\/>\n\t<\/div>\n<span class=\"wl-quantity wl-quantity-plus\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span><\/div><\/div><div class=\"wl-cart-wrap both\">\n\t<button type=\"submit\" class=\"single_add_to_cart_button button alt\">Afegir al carret<\/button>\n\n\t<\/div>               <ul class=\"wl-wishlist-compare-txt\">\n                                                       <\/ul> \n            \n\t<input type=\"hidden\" name=\"add-to-cart\" value=\"1875\" \/>\n\t<input type=\"hidden\" name=\"product_id\" value=\"1875\" \/>\n\t<input type=\"hidden\" name=\"variation_id\" class=\"variation_id\" value=\"0\" \/>\n<\/div>\n\t\t<\/div>\n\t\n\t<\/form>\n\n<div id=\"paypal-standard-container\"><\/div>                <\/div>\n                        <script type=\"text\/javascript\">\n                ;jQuery(document).ready(function($){ \n                    $('.elementor-element-059fe18 form.cart').on( 'click', 'span.wl-quantity-plus, span.wl-quantity-minus', function() {\n                        \n                        \/\/ Get current quantity values\n                                                    var qty = $( this ).closest( 'form.cart' ).find( '.qty' );\n                            var val = parseFloat(qty.val());\n                            var min_val = 1;\n                         \n                        var max  = parseFloat(qty.attr( 'max' ));\n                        var min  = parseFloat(qty.attr( 'min' ));\n                        var step = parseFloat(qty.attr( 'step' ));\n             \n                        \/\/ Change the value if plus or minus\n                        if ( $( this ).is( '.wl-quantity-plus' ) ) {\n                           if ( max && ( max <= val ) ) {\n                              qty.val( max );\n                           } \n                           else{\n                               qty.val( val + step );\n                            }\n                        } \n                        else {\n                           if ( min && ( min >= val ) ) {\n                              qty.val( min );\n                           } \n                           else if ( val > min_val ) {\n                              qty.val( val - step );\n                           }\n                        }\n                         \n                    });\n                });        \n            <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-732ac32 e-flex e-con-boxed e-con e-parent\" data-id=\"732ac32\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a53589 woolentor-columns-3 woolentor-columns-tablet-3 woolentor-columns-mobile-1 woolentor-badge-style-solid woolentor-badge-pos-top-left woolentor-card-hover-lift woolentor-image-hover-zoom elementor-widget elementor-widget-woolentor-product-grid-modern\" data-id=\"6a53589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woolentor-product-grid-modern.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woolentor-product-grid woolentor-style-modern woolentor-layout-grid woolentor-hover-fade-up\" data-wl-widget-name=\"woolentor-product-grid-modern\" data-wl-widget-settings=\"{&quot;style&quot;:&quot;modern&quot;,&quot;layout&quot;:&quot;grid&quot;,&quot;query_type&quot;:&quot;products&quot;,&quot;posts_per_page&quot;:6,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;categories&quot;:&quot;&quot;,&quot;tags&quot;:&quot;&quot;,&quot;exclude_out_of_stock&quot;:false,&quot;exclude_no_image&quot;:false,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;gap&quot;:25,&quot;gap_tablet&quot;:25,&quot;gap_mobile&quot;:20,&quot;show_image&quot;:true,&quot;image_size&quot;:&quot;woocommerce_thumbnail&quot;,&quot;show_secondary_image&quot;:false,&quot;show_title&quot;:true,&quot;title_tag&quot;:&quot;h3&quot;,&quot;title_length&quot;:0,&quot;show_price&quot;:true,&quot;show_rating&quot;:true,&quot;show_categories&quot;:true,&quot;show_excerpt&quot;:false,&quot;excerpt_length&quot;:20,&quot;show_add_to_cart&quot;:true,&quot;show_badges&quot;:true,&quot;show_stock_status&quot;:false,&quot;show_quick_view&quot;:true,&quot;show_wishlist&quot;:true,&quot;show_compare&quot;:true,&quot;hover_animation&quot;:&quot;fade-up&quot;,&quot;image_hover_effect&quot;:&quot;zoom&quot;,&quot;enable_pagination&quot;:false,&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;load_more_text&quot;:null,&quot;load_more_complete_text&quot;:null,&quot;custom_class&quot;:&quot;&quot;,&quot;enable_quick_cart&quot;:false,&quot;grid_id&quot;:&quot;woolentor-grid-6a57520d4e837&quot;,&quot;default_view_mode&quot;:&quot;grid&quot;,&quot;include_products&quot;:[],&quot;exclude_products&quot;:[&quot;10661&quot;,&quot;10751&quot;,&quot;1875&quot;],&quot;enable_filters&quot;:false,&quot;show_quick_actions&quot;:true,&quot;show_sale_badge&quot;:true,&quot;sale_badge_text&quot;:&quot;SALE&quot;,&quot;show_new_badge&quot;:true,&quot;new_badge_text&quot;:&quot;NEW&quot;,&quot;new_badge_days&quot;:7,&quot;show_trending_badge&quot;:false,&quot;trending_badge_text&quot;:&quot;HOT&quot;,&quot;badge_style&quot;:&quot;solid&quot;,&quot;badge_position&quot;:&quot;top-left&quot;,&quot;widget_name&quot;:&quot;woolentor-product-grid-modern&quot;,&quot;widget_id&quot;:&quot;6a53589&quot;,&quot;show_grid_description&quot;:false,&quot;grid_description_length&quot;:20,&quot;show_list_description&quot;:false,&quot;list_description_length&quot;:20,&quot;show_product_features&quot;:false,&quot;show_quantity_selector&quot;:false}\"><div class=\"woolentor-products-wrapper  \">\n<div class=\"woolentor-product-grid-modern woolentor-layout-grid  woolentor-columns-3\" id=\"woolentor-grid-6a57520d4e837\">\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"12695\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" title=\"Jarron Mawae Kai\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-kai\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12695\" title=\"Quick View\" aria-label=\"Jarron Mawae Kai\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                        Jarrones                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/' title='Jarron Mawae Kai'>Jarron Mawae Kai<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>130.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" data-quantity=\"1\" data-product_id=\"12695\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" title=\"Jarron Mawae Kai\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-kai\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12695\" title=\"Quick View\" aria-label=\"Jarron Mawae Kai\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                            Jarrones                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/' title='Jarron Mawae Kai'>Jarron Mawae Kai<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>130.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" data-quantity=\"1\" data-product_id=\"12695\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"12680\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/\" title=\"Jarr\u00f3n Mawae Nami\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-nami\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose.png 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12680\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Nami\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                        Jarrones                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/' title='Jarr\u00f3n Mawae Nami'>Jarr\u00f3n Mawae Nami<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/\" data-quantity=\"1\" data-product_id=\"12680\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/\" title=\"Jarr\u00f3n Mawae Nami\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-nami\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose.png 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12680\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Nami\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                            Jarrones                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/' title='Jarr\u00f3n Mawae Nami'>Jarr\u00f3n Mawae Nami<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/\" data-quantity=\"1\" data-product_id=\"12680\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"12610\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" title=\"Jarr\u00f3n Mawae Tuli\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-tuli\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12610\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Tuli\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                        Jarrones                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/' title='Jarr\u00f3n Mawae Tuli'>Jarr\u00f3n Mawae Tuli<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" data-quantity=\"1\" data-product_id=\"12610\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" title=\"Jarr\u00f3n Mawae Tuli\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-tuli\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12610\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Tuli\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                            Jarrones                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/' title='Jarr\u00f3n Mawae Tuli'>Jarr\u00f3n Mawae Tuli<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" data-quantity=\"1\" data-product_id=\"12610\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1817\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/\" title=\"Stonemoon\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png\" class=\"woolentor-product-img\" alt=\"stonemoon\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1817\" title=\"Quick View\" aria-label=\"Stonemoon\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/' title='Stonemoon'>Stonemoon<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>132.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1817\" data-quantity=\"1\" data-product_id=\"1817\" data-product_sku=\"stonemoon\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/\" title=\"Stonemoon\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png\" class=\"woolentor-product-img\" alt=\"stonemoon\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1817\" title=\"Quick View\" aria-label=\"Stonemoon\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/' title='Stonemoon'>Stonemoon<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>132.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1817\" data-quantity=\"1\" data-product_id=\"1817\" data-product_sku=\"stonemoon\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1957\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/\" title=\"Essential n\u00ba2\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png\" class=\"woolentor-product-img\" alt=\"essential-no2\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1957\" title=\"Quick View\" aria-label=\"Essential n\u00ba2\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/' title='Essential n\u00ba2'>Essential n\u00ba2<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>185.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1957\" data-quantity=\"1\" data-product_id=\"1957\" data-product_sku=\"essential-2\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/\" title=\"Essential n\u00ba2\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png\" class=\"woolentor-product-img\" alt=\"essential-no2\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1957\" title=\"Quick View\" aria-label=\"Essential n\u00ba2\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/' title='Essential n\u00ba2'>Essential n\u00ba2<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>185.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1957\" data-quantity=\"1\" data-product_id=\"1957\" data-product_sku=\"essential-2\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1941\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" title=\"Stratum\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png\" class=\"woolentor-product-img\" alt=\"stratum\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1941\" title=\"Quick View\" aria-label=\"Stratum\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/stratum\/' title='Stratum'>Stratum<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>230.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1941\" data-quantity=\"1\" data-product_id=\"1941\" data-product_sku=\"stratum\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" title=\"Stratum\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png\" class=\"woolentor-product-img\" alt=\"stratum\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1941\" title=\"Quick View\" aria-label=\"Stratum\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/stratum\/' title='Stratum'>Stratum<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>230.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/1875?add-to-cart=1941\" data-quantity=\"1\" data-product_id=\"1941\" data-product_sku=\"stratum\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n    \n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Plantcloud es una maceta colgante sostenible de cer\u00e1mica blanca brillante. Lleva una cinta de cuero vegetal elaborada con los restos de hojas de pi\u00f1a.<\/p>\n<p>Tiene un sistema muy pr\u00e1ctico para el riego y vaciado de agua.<\/p>\n<p><a href=\"https:\/\/basbarcelona.com\/ca\/?attachment_id=4044\/\" target=\"_blank\" rel=\"noopener\"><em>m\u00e1s informaci\u00f3n<\/em><\/a><\/p>","protected":false},"featured_media":1633,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":["post-1875","product","type-product","status-publish","has-post-thumbnail","product_cat-macetas-de-diseno","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=1875"}],"version-history":[{"count":3,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/1875\/revisions"}],"predecessor-version":[{"id":12987,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/1875\/revisions\/12987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media\/1633"}],"wp:attachment":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=1875"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_brand?post=1875"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat?post=1875"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_tag?post=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}