{"id":12680,"date":"2026-03-02T12:16:59","date_gmt":"2026-03-02T11:16:59","guid":{"rendered":"https:\/\/basbarcelona.com\/?post_type=product&#038;p=12680"},"modified":"2026-03-04T17:58:49","modified_gmt":"2026-03-04T16:58:49","slug":"jarron-mawae-nami","status":"publish","type":"product","link":"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/","title":{"rendered":"Vasi Mawae Nami"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"12680\" class=\"elementor elementor-12680\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5699acc2 e-flex e-con-boxed e-con e-parent\" data-id=\"5699acc2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6c8e8c94 e-con-full e-flex e-con e-child\" data-id=\"6c8e8c94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7def41a elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"7def41a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron Mawae Nami Rose\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Rose\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-rose.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Nacre\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-nacre.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Coral\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-coral.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno en ceramica mawae nami en mueble moderno\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-mueble-moderno.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno de ceramica mawae nami rose en escritorio\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-mawae-nami-rose-escritorio.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Seg\u00fcent\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Diapositivas Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron Mawae Nami Rose\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Nami-Rose.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Rose\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-rose.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Nacre\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-nacre.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno ceramica Mawae Nami Coral\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-coral.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno en ceramica mawae nami en mueble moderno\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-diseno-ceramica-mawae-nami-mueble-moderno.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Jarron diseno de ceramica mawae nami rose en escritorio\" style=\"background-image: url(&#039;https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/02\/Jarron-mawae-nami-rose-escritorio.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9a62df e-con-full e-flex e-con e-child\" data-id=\"a9a62df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39c32043 elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"39c32043\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t\t<h2 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Jarr\u00f3n Mawae Nami<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8fd9a6 elementor-widget elementor-widget-woocommerce-product-short-description\" data-id=\"1f8fd9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-short-description.default\">\n\t\t\t\t\t<div class=\"woocommerce-product-details__short-description\">\n\t<p>Jarr\u00f3n cer\u00e1mico de dise\u00f1o actual, modelado en gres de alta cocci\u00f3n y enriquecido con porcelana te\u00f1ida a partir de \u00f3xidos y minerales.<\/p>\n<p>En su acabado se aprecian peque\u00f1as incrustaciones minerales que aportan reflejos suaves y un caracter\u00edstico efecto brillante, resultado de sus finas estructuras cristalinas.<\/p>\n<p><strong>Medidas:<\/strong> alto 24 cm,\u00a0 di\u00e1metro mayor 10 cm<\/p>\n<p>Disponible en 3 tonalidades: Coral, Rose y Nacre.<\/p>\n<p>La tonalidad es similar a la presentada en las fotograf\u00edas, si bien las particularidades del trabajo artesanal confieren a cada jarr\u00f3n una identidad \u00fanica.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-252ed31 elementor-widget elementor-widget-image\" data-id=\"252ed31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2400\" height=\"1792\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores.jpeg\" class=\"attachment-full size-full wp-image-12821\" alt=\"\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores.jpeg 2400w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-300x224.jpeg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-1024x765.jpeg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-768x573.jpeg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-1536x1147.jpeg 1536w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-2048x1529.jpeg 2048w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-16x12.jpeg 16w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarrones-Mawae-Nami-3-colores-600x448.jpeg 600w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4535452f elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"4535452f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>150.00<\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfd32a7 elementor-widget-mobile__width-initial elementor-widget elementor-widget-wl-product-add-to-cart\" data-id=\"cfd32a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wl-product-add-to-cart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"wl-addto-cart variable wl-style-2 wl-show-status\">\n                    \n<form class=\"variations_form cart\" action=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-nami\/\" method=\"post\" enctype='multipart\/form-data' data-product_id=\"12680\" data-product_variations=\"[{&quot;attributes&quot;:{&quot;attribute_color&quot;:&quot;Coral&quot;},&quot;availability_html&quot;:&quot;&quot;,&quot;backorders_allowed&quot;:false,&quot;dimensions&quot;:{&quot;length&quot;:&quot;35&quot;,&quot;width&quot;:&quot;23&quot;,&quot;height&quot;:&quot;21&quot;},&quot;dimensions_html&quot;:&quot;35 &amp;times; 23 &amp;times; 21 cm&quot;,&quot;display_price&quot;:150,&quot;display_regular_price&quot;:150,&quot;gallery_image_ids&quot;:[],&quot;gallery_images_html&quot;:&quot;&quot;,&quot;image&quot;:{&quot;title&quot;:&quot;Mawae-Nami-Coral&quot;,&quot;caption&quot;:&quot;&quot;,&quot;url&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral.jpg&quot;,&quot;alt&quot;:&quot;Mawae-Nami-Coral&quot;,&quot;src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-600x600.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-600x600.jpg 600w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-300x300.jpg 300w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-1024x1024.jpg 1024w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-150x150.jpg 150w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-768x768.jpg 768w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-12x12.jpg 12w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-100x100.jpg 100w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral.jpg 1080w&quot;,&quot;sizes&quot;:&quot;(max-width: 600px) 100vw, 600px&quot;,&quot;full_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral.jpg&quot;,&quot;full_src_w&quot;:1080,&quot;full_src_h&quot;:1080,&quot;gallery_thumbnail_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-100x100.jpg&quot;,&quot;gallery_thumbnail_src_w&quot;:100,&quot;gallery_thumbnail_src_h&quot;:100,&quot;thumb_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Coral-600x600.jpg&quot;,&quot;thumb_src_w&quot;:600,&quot;thumb_src_h&quot;:600,&quot;src_w&quot;:600,&quot;src_h&quot;:600},&quot;image_id&quot;:12830,&quot;is_downloadable&quot;:false,&quot;is_in_stock&quot;:true,&quot;is_purchasable&quot;:true,&quot;is_sold_individually&quot;:&quot;yes&quot;,&quot;is_virtual&quot;:false,&quot;max_qty&quot;:1,&quot;min_qty&quot;:1,&quot;price_html&quot;:&quot;&quot;,&quot;sku&quot;:&quot;&quot;,&quot;variation_description&quot;:&quot;&quot;,&quot;variation_id&quot;:12825,&quot;variation_is_active&quot;:true,&quot;variation_is_visible&quot;:true,&quot;weight&quot;:&quot;1&quot;,&quot;weight_html&quot;:&quot;1 kg&quot;},{&quot;attributes&quot;:{&quot;attribute_color&quot;:&quot;Rose&quot;},&quot;availability_html&quot;:&quot;&quot;,&quot;backorders_allowed&quot;:false,&quot;dimensions&quot;:{&quot;length&quot;:&quot;35&quot;,&quot;width&quot;:&quot;23&quot;,&quot;height&quot;:&quot;21&quot;},&quot;dimensions_html&quot;:&quot;35 &amp;times; 23 &amp;times; 21 cm&quot;,&quot;display_price&quot;:150,&quot;display_regular_price&quot;:150,&quot;gallery_image_ids&quot;:[],&quot;gallery_images_html&quot;:&quot;&quot;,&quot;image&quot;:{&quot;title&quot;:&quot;Jarron-Mawae-Nami-Rose&quot;,&quot;caption&quot;:&quot;&quot;,&quot;url&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose.jpg&quot;,&quot;alt&quot;:&quot;Jarron Mawae Nami Rose&quot;,&quot;src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-600x600.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-600x600.jpg 600w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-300x300.jpg 300w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-1024x1024.jpg 1024w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-150x150.jpg 150w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-768x768.jpg 768w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-12x12.jpg 12w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-100x100.jpg 100w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose.jpg 1200w&quot;,&quot;sizes&quot;:&quot;(max-width: 600px) 100vw, 600px&quot;,&quot;full_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose.jpg&quot;,&quot;full_src_w&quot;:1200,&quot;full_src_h&quot;:1200,&quot;gallery_thumbnail_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-100x100.jpg&quot;,&quot;gallery_thumbnail_src_w&quot;:100,&quot;gallery_thumbnail_src_h&quot;:100,&quot;thumb_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Jarron-Mawae-Nami-Rose-600x600.jpg&quot;,&quot;thumb_src_w&quot;:600,&quot;thumb_src_h&quot;:600,&quot;src_w&quot;:600,&quot;src_h&quot;:600},&quot;image_id&quot;:12687,&quot;is_downloadable&quot;:false,&quot;is_in_stock&quot;:true,&quot;is_purchasable&quot;:true,&quot;is_sold_individually&quot;:&quot;yes&quot;,&quot;is_virtual&quot;:false,&quot;max_qty&quot;:1,&quot;min_qty&quot;:1,&quot;price_html&quot;:&quot;&quot;,&quot;sku&quot;:&quot;&quot;,&quot;variation_description&quot;:&quot;&quot;,&quot;variation_id&quot;:12827,&quot;variation_is_active&quot;:true,&quot;variation_is_visible&quot;:true,&quot;weight&quot;:&quot;1&quot;,&quot;weight_html&quot;:&quot;1 kg&quot;},{&quot;attributes&quot;:{&quot;attribute_color&quot;:&quot;Nacre&quot;},&quot;availability_html&quot;:&quot;&quot;,&quot;backorders_allowed&quot;:false,&quot;dimensions&quot;:{&quot;length&quot;:&quot;35&quot;,&quot;width&quot;:&quot;23&quot;,&quot;height&quot;:&quot;21&quot;},&quot;dimensions_html&quot;:&quot;35 &amp;times; 23 &amp;times; 21 cm&quot;,&quot;display_price&quot;:150,&quot;display_regular_price&quot;:150,&quot;gallery_image_ids&quot;:[],&quot;gallery_images_html&quot;:&quot;&quot;,&quot;image&quot;:{&quot;title&quot;:&quot;Mawae-Nami-Nacre&quot;,&quot;caption&quot;:&quot;&quot;,&quot;url&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre.jpg&quot;,&quot;alt&quot;:&quot;Mawae-Nami-Nacre&quot;,&quot;src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-600x600.jpg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-600x600.jpg 600w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-300x300.jpg 300w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-1024x1024.jpg 1024w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-150x150.jpg 150w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-768x768.jpg 768w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-12x12.jpg 12w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-100x100.jpg 100w, https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre.jpg 1080w&quot;,&quot;sizes&quot;:&quot;(max-width: 600px) 100vw, 600px&quot;,&quot;full_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre.jpg&quot;,&quot;full_src_w&quot;:1080,&quot;full_src_h&quot;:1080,&quot;gallery_thumbnail_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-100x100.jpg&quot;,&quot;gallery_thumbnail_src_w&quot;:100,&quot;gallery_thumbnail_src_h&quot;:100,&quot;thumb_src&quot;:&quot;https:\\\/\\\/basbarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mawae-Nami-Nacre-600x600.jpg&quot;,&quot;thumb_src_w&quot;:600,&quot;thumb_src_h&quot;:600,&quot;src_w&quot;:600,&quot;src_h&quot;:600},&quot;image_id&quot;:12831,&quot;is_downloadable&quot;:false,&quot;is_in_stock&quot;:true,&quot;is_purchasable&quot;:true,&quot;is_sold_individually&quot;:&quot;yes&quot;,&quot;is_virtual&quot;:false,&quot;max_qty&quot;:1,&quot;min_qty&quot;:1,&quot;price_html&quot;:&quot;&quot;,&quot;sku&quot;:&quot;&quot;,&quot;variation_description&quot;:&quot;&quot;,&quot;variation_id&quot;:12826,&quot;variation_is_active&quot;:true,&quot;variation_is_visible&quot;:true,&quot;weight&quot;:&quot;1&quot;,&quot;weight_html&quot;:&quot;1 kg&quot;}]\">\n\t\n\t\t\t<table class=\"variations\" cellspacing=\"0\" role=\"presentation\">\n\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t<th class=\"label\"><label for=\"color\">Color:<\/label><\/th>\n\t\t\t\t\t\t<td class=\"value\">\n\t\t\t\t\t\t\t<select id=\"color\" class=\"\" name=\"attribute_color\" data-attribute_name=\"attribute_color\" data-show_option_none=\"yes\"><option value=\"\">Trieu una opci\u00f3<\/option><option value=\"Coral\" >Coral<\/option><option value=\"Nacre\" >Nacre<\/option><option value=\"Rose\" >Rose<\/option><\/select><a class=\"reset_variations\" href=\"#\" aria-label=\"Neteja les opcions\">Neteja<\/a>\t\t\t\t\t\t<\/td>\n\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t<\/table>\n\t\t<div class=\"reset_variations_alert screen-reader-text\" role=\"alert\" aria-live=\"polite\" aria-relevant=\"all\"><\/div>\n\t\t\t\t\n\t\t<div class=\"single_variation_wrap\">\n\t\t\t<div class=\"woocommerce-variation single_variation\" role=\"alert\" aria-relevant=\"additions\"><\/div><div class=\"woocommerce-variation-add-to-cart variations_button\">\n\t\n\t<div class=\"quantity\">\n\t\t<label class=\"screen-reader-text\" for=\"quantity_6a5751cdda0f5\">quantitat de Jarr\u00f3n Mawae Nami<\/label>\n\t<input\n\t\ttype=\"hidden\"\n\t\t\t\tid=\"quantity_6a5751cdda0f5\"\n\t\tclass=\"input-text qty text\"\n\t\tname=\"quantity\"\n\t\tvalue=\"1\"\n\t\taria-label=\"Quantitat de producte\"\n\t\t\t\tmin=\"1\"\n\t\t\t\t\tmax=\"1\"\n\t\t\t\t\t\t\tstep=\"1\"\n\t\t\tplaceholder=\"\"\n\t\t\tinputmode=\"numeric\"\n\t\t\tautocomplete=\"off\"\n\t\t\t\/>\n\t<\/div>\n\n\t<button type=\"submit\" class=\"single_add_to_cart_button button alt\">Afegir al carret<\/button>\n\n\t\n\t<input type=\"hidden\" name=\"add-to-cart\" value=\"12680\" \/>\n\t<input type=\"hidden\" name=\"product_id\" value=\"12680\" \/>\n\t<input type=\"hidden\" name=\"variation_id\" class=\"variation_id\" value=\"0\" \/>\n<\/div>\n\t\t<\/div>\n\t\n\t<\/form>\n\n<div id=\"paypal-standard-container\"><\/div>                <\/div>\n                        <script type=\"text\/javascript\">\n                ;jQuery(document).ready(function($){ \n                    $('.elementor-element-cfd32a7 form.cart').on( 'click', 'span.wl-quantity-plus, span.wl-quantity-minus', function() {\n                        \n                        \/\/ Get current quantity values\n                                                    var qty = $( this ).closest( 'form.cart' ).find( '.qty' );\n                            var val = parseFloat(qty.val());\n                            var min_val = 1;\n                         \n                        var max  = parseFloat(qty.attr( 'max' ));\n                        var min  = parseFloat(qty.attr( 'min' ));\n                        var step = parseFloat(qty.attr( 'step' ));\n             \n                        \/\/ Change the value if plus or minus\n                        if ( $( this ).is( '.wl-quantity-plus' ) ) {\n                           if ( max && ( max <= val ) ) {\n                              qty.val( max );\n                           } \n                           else{\n                               qty.val( val + step );\n                            }\n                        } \n                        else {\n                           if ( min && ( min >= val ) ) {\n                              qty.val( min );\n                           } \n                           else if ( val > min_val ) {\n                              qty.val( val - step );\n                           }\n                        }\n                         \n                    });\n                });        \n            <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26a45e6 e-flex e-con-boxed e-con e-parent\" data-id=\"26a45e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3edf37b woolentor-columns-3 woolentor-columns-tablet-3 woolentor-columns-mobile-1 woolentor-badge-style-solid woolentor-badge-pos-top-left woolentor-card-hover-lift woolentor-image-hover-zoom elementor-widget elementor-widget-woolentor-product-grid-modern\" data-id=\"3edf37b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woolentor-product-grid-modern.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woolentor-product-grid woolentor-style-modern woolentor-layout-grid woolentor-hover-fade-up\" data-wl-widget-name=\"woolentor-product-grid-modern\" data-wl-widget-settings=\"{&quot;style&quot;:&quot;modern&quot;,&quot;layout&quot;:&quot;grid&quot;,&quot;query_type&quot;:&quot;products&quot;,&quot;posts_per_page&quot;:6,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;categories&quot;:[],&quot;tags&quot;:&quot;&quot;,&quot;exclude_out_of_stock&quot;:false,&quot;exclude_no_image&quot;:false,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;gap&quot;:25,&quot;gap_tablet&quot;:25,&quot;gap_mobile&quot;:20,&quot;show_image&quot;:true,&quot;image_size&quot;:&quot;woocommerce_thumbnail&quot;,&quot;show_secondary_image&quot;:false,&quot;show_title&quot;:true,&quot;title_tag&quot;:&quot;h3&quot;,&quot;title_length&quot;:0,&quot;show_price&quot;:true,&quot;show_rating&quot;:true,&quot;show_categories&quot;:true,&quot;show_excerpt&quot;:false,&quot;excerpt_length&quot;:20,&quot;show_add_to_cart&quot;:true,&quot;show_badges&quot;:true,&quot;show_stock_status&quot;:false,&quot;show_quick_view&quot;:true,&quot;show_wishlist&quot;:true,&quot;show_compare&quot;:true,&quot;hover_animation&quot;:&quot;fade-up&quot;,&quot;image_hover_effect&quot;:&quot;zoom&quot;,&quot;enable_pagination&quot;:true,&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;load_more_text&quot;:null,&quot;load_more_complete_text&quot;:null,&quot;custom_class&quot;:&quot;&quot;,&quot;enable_quick_cart&quot;:false,&quot;grid_id&quot;:&quot;woolentor-grid-6a5751cddc266&quot;,&quot;default_view_mode&quot;:&quot;grid&quot;,&quot;include_products&quot;:[],&quot;exclude_products&quot;:[&quot;10661&quot;,&quot;10751&quot;,&quot;12680&quot;],&quot;enable_filters&quot;:false,&quot;show_quick_actions&quot;:true,&quot;show_sale_badge&quot;:true,&quot;sale_badge_text&quot;:&quot;SALE&quot;,&quot;show_new_badge&quot;:true,&quot;new_badge_text&quot;:&quot;NEW&quot;,&quot;new_badge_days&quot;:7,&quot;show_trending_badge&quot;:false,&quot;trending_badge_text&quot;:&quot;HOT&quot;,&quot;badge_style&quot;:&quot;solid&quot;,&quot;badge_position&quot;:&quot;top-left&quot;,&quot;widget_name&quot;:&quot;woolentor-product-grid-modern&quot;,&quot;widget_id&quot;:&quot;3edf37b&quot;,&quot;show_grid_description&quot;:false,&quot;grid_description_length&quot;:20,&quot;show_list_description&quot;:false,&quot;list_description_length&quot;:20,&quot;show_product_features&quot;:false,&quot;show_quantity_selector&quot;:false}\"><div class=\"woolentor-products-wrapper  \">\n<div class=\"woolentor-product-grid-modern woolentor-layout-grid  woolentor-columns-3\" id=\"woolentor-grid-6a5751cddc266\">\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"12695\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" title=\"Jarron Mawae Kai\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-kai\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12695\" title=\"Quick View\" aria-label=\"Jarron Mawae Kai\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                        Jarrones                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/' title='Jarron Mawae Kai'>Jarron Mawae Kai<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>130.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" data-quantity=\"1\" data-product_id=\"12695\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" title=\"Jarron Mawae Kai\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-kai\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Mawae-Kai-rose.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12695\" title=\"Quick View\" aria-label=\"Jarron Mawae Kai\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                            Jarrones                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/' title='Jarron Mawae Kai'>Jarron Mawae Kai<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>130.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-kai\/\" data-quantity=\"1\" data-product_id=\"12695\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"12610\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" title=\"Jarr\u00f3n Mawae Tuli\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-tuli\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12610\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Tuli\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                        Jarrones                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/' title='Jarr\u00f3n Mawae Tuli'>Jarr\u00f3n Mawae Tuli<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" data-quantity=\"1\" data-product_id=\"12610\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" title=\"Jarr\u00f3n Mawae Tuli\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png\" class=\"woolentor-product-img\" alt=\"jarron-mawae-tuli\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-12x12.png 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/03\/Jarron-Mawae-Tuli-coral.png 1080w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"12610\" title=\"Quick View\" aria-label=\"Jarr\u00f3n Mawae Tuli\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/jarrones\/\" class=\"woolentor-product-category\">\n                                            Jarrones                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/' title='Jarr\u00f3n Mawae Tuli'>Jarr\u00f3n Mawae Tuli<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/jarron-mawae-tuli\/\" data-quantity=\"1\" data-product_id=\"12610\" data-product_sku=\"\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1817\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/\" title=\"Stonemoon\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png\" class=\"woolentor-product-img\" alt=\"stonemoon\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1817\" title=\"Quick View\" aria-label=\"Stonemoon\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/' title='Stonemoon'>Stonemoon<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>132.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1817\" data-quantity=\"1\" data-product_id=\"1817\" data-product_sku=\"stonemoon\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/\" title=\"Stonemoon\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png\" class=\"woolentor-product-img\" alt=\"stonemoon\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Maceta-de-pared-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1817\" title=\"Quick View\" aria-label=\"Stonemoon\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/lluna-de-pedra\/' title='Stonemoon'>Stonemoon<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>132.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1817\" data-quantity=\"1\" data-product_id=\"1817\" data-product_sku=\"stonemoon\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1957\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/\" title=\"Essential n\u00ba2\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png\" class=\"woolentor-product-img\" alt=\"essential-no2\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1957\" title=\"Quick View\" aria-label=\"Essential n\u00ba2\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/' title='Essential n\u00ba2'>Essential n\u00ba2<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>185.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1957\" data-quantity=\"1\" data-product_id=\"1957\" data-product_sku=\"essential-2\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/\" title=\"Essential n\u00ba2\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png\" class=\"woolentor-product-img\" alt=\"essential-no2\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8259_D-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1957\" title=\"Quick View\" aria-label=\"Essential n\u00ba2\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/essential-no2\/' title='Essential n\u00ba2'>Essential n\u00ba2<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>185.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1957\" data-quantity=\"1\" data-product_id=\"1957\" data-product_sku=\"essential-2\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1941\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" title=\"Stratum\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png\" class=\"woolentor-product-img\" alt=\"stratum\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1941\" title=\"Quick View\" aria-label=\"Stratum\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/stratum\/' title='Stratum'>Stratum<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>230.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1941\" data-quantity=\"1\" data-product_id=\"1941\" data-product_sku=\"stratum\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" title=\"Stratum\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png\" class=\"woolentor-product-img\" alt=\"stratum\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/MG_8315-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1941\" title=\"Quick View\" aria-label=\"Stratum\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/stratum\/' title='Stratum'>Stratum<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>230.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"\/ca\/wp-json\/wp\/v2\/product\/12680?add-to-cart=1941\" data-quantity=\"1\" data-product_id=\"1941\" data-product_sku=\"stratum\" class=\"woolentor-cart-btn button product_type_simple add_to_cart_button ajax_add_to_cart\" title=\"Afegir al carret\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Afegir al carret<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n            \n        <div class=\"product woolentor-product-item\" data-product-id=\"1875\">\n            <div class=\"woolentor-product-card woolentor-grid-card  \">\n\n                <!-- GRID VIEW CONTENT -->\n                <div class=\"woolentor-grid-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/\" title=\"Plantcloud\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-600x600.png\" class=\"woolentor-product-img\" alt=\"plantcloud-maceta-colgante\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1875\" title=\"Quick View\" aria-label=\"Plantcloud\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                                                    <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                                                    <div class=\"woolentor-product-categories\">\n                                                                    <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                        macetas de dise\u00f1o                                    <\/a>\n                                                            <\/div>\n                        \n                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/' title='Plantcloud'>Plantcloud<\/a><\/h3>\n                        \n                        \n                                                    <div class=\"woolentor-product-price\">\n                                <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>242.00<\/span>                                                            <\/div>\n                        \n                                                    <div class=\"woolentor-product-actions\">\n                                <a href=\"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/\" data-quantity=\"1\" data-product_id=\"1875\" data-product_sku=\"plantcloud\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                            <\/div>\n                                            <\/div>\n                <\/div>\n                <!-- END GRID VIEW CONTENT -->\n                \n                <!-- LIST VIEW CONTENT -->\n                <div class=\"woolentor-list-view-content\">\n\n                                            <div class=\"woolentor-product-image\">\n                            <a href=\"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/\" title=\"Plantcloud\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-600x600.png\" class=\"woolentor-product-img\" alt=\"plantcloud-maceta-colgante\" loading=\"lazy\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/plancloud-sombra-100x100.png 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" title=\"\">                            <\/a>\n                            \n                                                                <!-- Badges -->\n                                    <div class=\"woolentor-badges\">\n                                        \n                                        \n                                                                            <\/div>\n                                \n                                                            <div class=\"woolentor-quick-actions\">\n                                    \n                                                                            <button class=\"woolentor-quick-action woolentor-quickview-btn woolentorquickview\" data-product_id=\"1875\" title=\"Quick View\" aria-label=\"Plantcloud\">\n                                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\">\n                                                <path d=\"M1 12s4-8 11-8 11 8 11 8-4 8-11 8-11-8-11-8z\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                                <circle cx=\"12\" cy=\"12\" r=\"3\" stroke=\"currentColor\" stroke-width=\"2\"\/>\n                                            <\/svg>\n                                        <\/button>\n                                    \n                                                                    <\/div>\n                            \n                        <\/div>\n                    \n                    <div class=\"woolentor-product-content\">\n                        <div class=\"woolentor-content-header\">\n                                                            <div class=\"woolentor-product-categories\">\n                                                                            <a href=\"https:\/\/basbarcelona.com\/ca\/macetas-de-diseno\/\" class=\"woolentor-product-category\">\n                                            macetas de dise\u00f1o                                        <\/a>\n                                                                    <\/div>\n                                                        <h3 class='woolentor-product-title'><a href='https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/' title='Plantcloud'>Plantcloud<\/a><\/h3>                        <\/div>\n\n                        \n                        \n                        \n                        <div class=\"woolentor-content-footer\">\n                            <div class=\"woolentor-price-stock\">\n                                                                    <div class=\"woolentor-product-price\">\n                                        <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>242.00<\/span>                                                                            <\/div>\n                                                            <\/div>\n\n                                                            <div class=\"woolentor-product-actions\">\n\n                                                                        \n                                    \n                                    <a href=\"https:\/\/basbarcelona.com\/ca\/product\/plantcloud-maceta-colgante\/\" data-quantity=\"1\" data-product_id=\"1875\" data-product_sku=\"plantcloud\" class=\"woolentor-cart-btn button product_type_variable add_to_cart_button\" title=\"Selecciona opcions\" rel=\"nofollow\"><svg class=\"cart-icon\" fill=\"none\" stroke=\"currentColor\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M16 11V7a4 4 0 00-8 0v4M5 9h14l1 12H4L5 9z\"><\/path><\/svg>Selecciona opcions<\/a>                                    \n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END LIST VIEW CONTENT -->\n\n            <\/div>\n        <\/div>\n\n    \n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jarr\u00f3n cer\u00e1mico de dise\u00f1o actual, modelado en gres de alta cocci\u00f3n y enriquecido con porcelana te\u00f1ida a partir de \u00f3xidos y minerales.<\/p>\n<p>En su acabado se aprecian peque\u00f1as incrustaciones minerales que aportan reflejos suaves y un caracter\u00edstico efecto brillante, resultado de sus finas estructuras cristalinas.<\/p>\n<p><strong>Medidas:<\/strong> alto 24 cm,\u00a0 di\u00e1metro mayor 10 cm<\/p>\n<p>Disponible en 3 tonalidades: Coral, Rose y Nacre.<\/p>\n<p>La tonalidad es similar a la presentada en las fotograf\u00edas, si bien las particularidades del trabajo artesanal confieren a cada jarr\u00f3n una identidad \u00fanica.<\/p>","protected":false},"featured_media":12795,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"product_brand":[],"product_cat":[93],"product_tag":[],"class_list":["post-12680","product","type-product","status-publish","has-post-thumbnail","product_cat-jarrones","first","instock","sold-individually","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/12680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=12680"}],"version-history":[{"count":47,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/12680\/revisions"}],"predecessor-version":[{"id":12939,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product\/12680\/revisions\/12939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media\/12795"}],"wp:attachment":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=12680"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_brand?post=12680"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat?post=12680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/product_tag?post=12680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}