{"id":1184,"date":"2020-11-05T18:08:22","date_gmt":"2020-11-05T17:08:22","guid":{"rendered":"https:\/\/basbarcelona.com\/?page_id=1184"},"modified":"2026-07-08T19:22:33","modified_gmt":"2026-07-08T17:22:33","slug":"macetero-elegante-ceramica","status":"publish","type":"page","link":"https:\/\/basbarcelona.com\/ca\/test-ceramica-elegant\/","title":{"rendered":"Stratum"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1184\" class=\"elementor elementor-1184\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca6ae05 e-flex e-con-boxed e-con e-parent\" data-id=\"ca6ae05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f006a4 e-con-full e-flex e-con e-child\" data-id=\"3f006a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c68a9a4 elementor-widget elementor-widget-heading\" data-id=\"c68a9a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stratum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce9f81d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ce9f81d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4331677 elementor-widget elementor-widget-heading\" data-id=\"4331677\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Espl\u00e8ndida i suntuosa \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7eaf726 e-con-full e-flex e-con e-parent\" data-id=\"7eaf726\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b01a642 e-con-full e-flex e-con e-child\" data-id=\"b01a642\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df1730f elementor-widget elementor-widget-heading\" data-id=\"df1730f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Font de vida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b958f0 elementor-widget elementor-widget-heading\" data-id=\"5b958f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Macetero elegante de cer\u00e1mica artesanal<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f584e84 elementor-widget elementor-widget-text-editor\" data-id=\"f584e84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>De l'essencial brolla la vida, com una font que emana i ressorgeix des de l'interior de la terra.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00af337 elementor-align-left elementor-mobile-align-center elementor-tablet-align-left elementor-widget elementor-widget-button\" data-id=\"00af337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Veure test elegant stratum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-307c7d4 e-con-full e-flex e-con e-child\" data-id=\"307c7d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3b2f2b elementor-widget elementor-widget-image\" data-id=\"d3b2f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e.jpg\" class=\"attachment-large size-large wp-image-10103\" alt=\"maceter de cer\u00e0mica artesanal elegant\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e-300x200.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e-768x512.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e-18x12.jpg 18w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/11\/cca5ea22-6bc6-473d-8855-eef4136e669e-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90494da e-con-full e-flex e-con e-parent\" data-id=\"90494da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-72274e1 e-con-full e-flex e-con e-child\" data-id=\"72274e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-335d521 elementor-widget elementor-widget-video\" data-id=\"335d521\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-ilustracion.mp4\" autoplay=\"\" loop=\"\" playsinline=\"\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4d08a6 e-con-full e-flex e-con e-child\" data-id=\"d4d08a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc0b760 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"bc0b760\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"tabs.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1971\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1971\" aria-expanded=\"false\">Descripci\u00f3<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1972\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1972\" aria-expanded=\"false\">Detalls<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1971\" aria-expanded=\"false\">Descripci\u00f3<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1971\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1971\" tabindex=\"0\" hidden=\"false\"><p class=\"translation-block\"><strong>Test elegant de cer\u00e0mica elaborat<\/strong> artesanalment, recomanat per a plantes que creixen des del centre, la seva forma real\u00e7a l'est\u00e8tica d'aquestes plantes.<\/p><p>Aquesta torreta est\u00e0 inspirada en els estrats de la terra, porta una franja de bronze simbolitzant la puresa mineral i un acabat d'\u00f2xids naturals a la seva base representant les profunditats de la terra.<\/p><p>La seva base ha estat dissenyada per recollir l'aigua del reg i \u00e9s totalment impermeable; t\u00e9 el revers llis i suau garantint aix\u00ed que els mobles i taules no es malmetin.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1972\" aria-expanded=\"false\">Detalls<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1972\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1972\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\">Acabats: cer\u00e0mica blanca brillant + bronze + \u00f2xids cer\u00e0mics + vitrificats<img decoding=\"async\" class=\"wp-image-1212 alignright\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/12\/E5-dibujo.png\" alt=\"\" width=\"211\" height=\"146\" title=\"\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/12\/E5-dibujo.png 727w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/12\/E5-dibujo-300x208.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2020\/12\/E5-dibujo-600x416.png 600w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/p><div class=\"woocommerce-product-details__short-description\"><p style=\"text-align: left;\">Recomanada per a tot tipus de plantes i especialment per a les que creixen des del centre.<\/p><p style=\"text-align: left;\" class=\"translation-block\">Plat integrat i vitrificat per a la recollida d'aigua.<br><em>Di\u00e0metre 20,5 cm \/ Al\u00e7ada 12 cm \/ Pes 1895g<\/em><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a0f90b e-con-full e-flex e-con e-parent\" data-id=\"7a0f90b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e2c1b3e e-con-full e-flex e-con e-child\" data-id=\"e2c1b3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb6f0fd elementor-widget elementor-widget-image\" data-id=\"cb6f0fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"588\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-detalle-stratum-1024x753.jpg\" class=\"attachment-large size-large wp-image-4877\" alt=\"Detall de test de strat.\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-detalle-stratum.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-detalle-stratum-300x221.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-detalle-stratum-768x565.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/07\/maceta-detalle-stratum-600x441.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc7758d e-con-full e-flex e-con e-child\" data-id=\"dc7758d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20be8da elementor-widget elementor-widget-image\" data-id=\"20be8da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2048\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo.jpg\" class=\"attachment-full size-full wp-image-12225\" alt=\"Macetero elegant amb Monstera Albo\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo.jpg 2048w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-300x300.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-1024x1024.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-150x150.jpg 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-768x768.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-1536x1536.jpg 1536w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-12x12.jpg 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-600x600.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2023\/02\/Macetero-con-monstera-albo-100x100.jpg 100w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cffa718 animated-slow elementor-widget elementor-widget-heading\" data-id=\"cffa718\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">La vida brolla...<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec317ea e-con-full e-flex e-con e-parent\" data-id=\"ec317ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7eaa7f5 e-con-full e-flex e-con e-child\" data-id=\"7eaa7f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ca347 elementor-widget elementor-widget-image\" data-id=\"e6ca347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-1024x1024.png\" class=\"attachment-large size-large wp-image-1949\" alt=\"Mantell terrestre amb platell\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-1024x1024.png 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-150x150.png 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-300x300.png 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-768x768.png 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-500x500.png 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-600x600.png 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato-100x100.png 100w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-plato.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d9af9 elementor-align-center elementor-mobile-align-center elementor-tablet-align-left elementor-widget elementor-widget-button\" data-id=\"40d9af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/basbarcelona.com\/ca\/product\/stratum\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar test stratum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e2b394 e-con-full e-flex e-con e-child\" data-id=\"9e2b394\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10ba286 elementor-widget elementor-widget-image\" data-id=\"10ba286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/xenia-retocando-stratum-1024x683.jpg\" class=\"attachment-large size-large wp-image-1650\" alt=\"Xenia continua retocant\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/xenia-retocando-stratum.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/xenia-retocando-stratum-300x200.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/xenia-retocando-stratum-768x512.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/xenia-retocando-stratum-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68313da e-con-full e-flex e-con e-parent\" data-id=\"68313da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2aa2726 e-con-full e-flex e-con e-child\" data-id=\"2aa2726\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0d7b5 elementor-widget elementor-widget-image\" data-id=\"1d0d7b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"761\" height=\"761\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas.jpg\" class=\"attachment-large size-large wp-image-12196\" alt=\"macetero elegant bas\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas.jpg 761w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas-300x300.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas-150x150.jpg 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas-12x12.jpg 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas-600x600.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Macetero-elegante-bas-100x100.jpg 100w\" sizes=\"(max-width: 761px) 100vw, 761px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b282c elementor-widget elementor-widget-image\" data-id=\"13b282c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-1024x1024.jpg\" class=\"attachment-large size-large wp-image-1617\" alt=\"Xenia Bas numerant el test de terra\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-150x150.jpg 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-300x300.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-768x768.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-500x500.jpg 500w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-600x600.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Xenia-numerando-stratum-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5b0e65 e-con-full e-flex e-con e-child\" data-id=\"d5b0e65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-640a194 elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"640a194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1664\" height=\"1664\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum.jpg\" class=\"attachment-full size-full wp-image-12483\" alt=\"Base per a test-planter stratum\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum.jpg 1664w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-300x300.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-1024x1024.jpg 1024w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-150x150.jpg 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-768x768.jpg 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-1536x1536.jpg 1536w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-12x12.jpg 12w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-600x600.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2026\/01\/Base-macetero-stratum-100x100.jpg 100w\" sizes=\"(max-width: 1664px) 100vw, 1664px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30fb08f e-con-full e-flex e-con e-child\" data-id=\"30fb08f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49c1c0a elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"49c1c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Numeraci\u00f3 exclusiva \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd5b3fd elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"cd5b3fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">per X\u00e8nia Bas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c799fd9 elementor-widget elementor-widget-text-editor\" data-id=\"c799fd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Totes les <strong>torretes Stratum<\/strong> estan numerades i signades una a una per la ceramista X\u00e8nia Bas.<\/p><p>El treball artesanal de cada pe\u00e7a fa que no n'hi hagi cap d'igual.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43c0604 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"43c0604\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02b3f23 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"02b3f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17efebf elementor-widget elementor-widget-heading\" data-id=\"17efebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vols saber per qu\u00e8 aquests testos poden donar pau a la teva casa?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2118ed9 elementor-hidden-desktop elementor-hidden-tablet elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"2118ed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-97d8ac4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"testera de disseny\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/basbarcelona.com\/ca\/essential-n2\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Essencial n\u00fam. 2<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-542876f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Test de prova\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/basbarcelona.com\/ca\/torreta-penjadora\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Plantcloud<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-2c1bdc9 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Maceter de paret\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/basbarcelona.com\/ca\/stonemoon\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Stonemoon<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2298dd0 e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"2298dd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6c0047 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c6c0047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f87ded elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"1f87ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vols saber per qu\u00e8 aquests testos de cer\u00e0mica poden donar pau a casa teva?<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0f4d2f e-con-full e-flex e-con e-child\" data-id=\"a0f4d2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24e28a6 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"24e28a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vols saber per qu\u00e8 aquests testos de cer\u00e0mica poden donar pau a casa teva?<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d6fc130 e-grid e-con-boxed e-con e-child\" data-id=\"d6fc130\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d21b52e elementor-widget elementor-widget-image\" data-id=\"d21b52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/basbarcelona.com\/ca\/essential-n2\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"889\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2-921x1024.webp\" class=\"attachment-large size-large wp-image-7842\" alt=\"dissenyar test\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2-921x1024.webp 921w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2-270x300.webp 270w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2-768x854.webp 768w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2-600x667.webp 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/essential-n2.webp 1000w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94c7743 elementor-widget elementor-widget-image\" data-id=\"94c7743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/basbarcelona.com\/ca\/torreta-penjadora\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"583\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Maceta-colgar-plantcloud.jpg\" class=\"attachment-large size-large wp-image-7844\" alt=\"Plantador penjant\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Maceta-colgar-plantcloud.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Maceta-colgar-plantcloud-300x292.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96d7cdc elementor-widget elementor-widget-image\" data-id=\"96d7cdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/basbarcelona.com\/ca\/test-de-paret\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Stonemoon-maceta-pared.jpg\" class=\"attachment-large size-large wp-image-7834\" alt=\"Maceter de paret\" srcset=\"https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Stonemoon-maceta-pared.jpg 600w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Stonemoon-maceta-pared-300x300.jpg 300w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Stonemoon-maceta-pared-150x150.jpg 150w, https:\/\/basbarcelona.com\/wp-content\/uploads\/2022\/05\/Stonemoon-maceta-pared-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Stratum Espl\u00e9ndida y suntuosa Fuente de vida Macetero elegante de cer\u00e1mica artesanal De lo esencial brota la vida, como una fuente que emana y resurge desde el interior de la tierra. Ver Maceta elegante stratum https:\/\/basbarcelona.com\/wp-content\/uploads\/2021\/05\/Stratum-ilustracion.mp4 Descripci\u00f3n Detalles Descripci\u00f3n Maceta elegante de cer\u00e1mica elaborada artesanalmente, recomendada para plantas que crecen desde el centro, su forma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12196,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1184","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":18,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/1184\/revisions"}],"predecessor-version":[{"id":13418,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/1184\/revisions\/13418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media\/12196"}],"wp:attachment":[{"href":"https:\/\/basbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}